{"id":33,"date":"2023-04-11T17:45:43","date_gmt":"2023-04-11T15:45:43","guid":{"rendered":"https:\/\/ambasciatapraga.esteri.it\/?page_id=33"},"modified":"2023-04-11T17:45:43","modified_gmt":"2023-04-11T15:45:43","slug":"dall_ambasciata","status":"publish","type":"page","link":"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/","title":{"rendered":"Dall&#8217;Ambasciata"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>Inserisci i parametri di ricerca                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">Dal<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">Al<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">Campo ricerca libera<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">Mostra risultati<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 13 Agosto 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/premio-per-ricercatrici-ricercatori-e-startup-premio-farnesina-premio-linnovazione-che-parla-italiano-premio-science-she-says\/\" title=\"Premio per ricercatrici, ricercatori e startup: Premio Farnesina, Premio \u201cl\u2019Innovazione che parla italiano\u201d, Premio \u201cScience, She says!\u201d\">Premio per ricercatrici, ricercatori e startup: Premio Farnesina, Premio \u201cl\u2019Innovazione che parla italiano\u201d, Premio \u201cScience, She says!\u201d<\/a><\/h5>\n                            <p class=\"card-text\">Candidature aperte: scadenza 24 settembre 2026. Anche quest\u2019anno il Ministero degli Affari Esteri e della Cooperazione Internazionale indice i bandi per l\u2019assegnazione dei premi dedicati alla cooperazione scientifica, all\u2019innovazione italiana all&#8217;estero e alle giovani scienziate di Paesi stranieri. Gli interessati che possiedano i requisiti previsti dai bandi possono avanzare le proprie candidature entro le date [&hellip;]<\/p>\n                                <a title=\"Premio per ricercatrici, ricercatori e startup: Premio Farnesina, Premio \u201cl\u2019Innovazione che parla italiano\u201d, Premio \u201cScience, She says!\u201d\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/premio-per-ricercatrici-ricercatori-e-startup-premio-farnesina-premio-linnovazione-che-parla-italiano-premio-science-she-says\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 7 Agosto 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/message-from-the-vice-president-of-the-council-of-ministers-and-minister-of-foreign-affairs-and-international-cooperation-antonio-tajani-on-the-occasion-of-the-70th-anniversary-of-the-marcinelle-tra\/\" title=\"MESSAGE FROM THE VICE PRESIDENT OF THE COUNCIL OF MINISTERS AND MINISTER OF FOREIGN AFFAIRS AND INTERNATIONAL COOPERATION, ANTONIO TAJANI, ON THE OCCASION OF THE 70TH ANNIVERSARY OF THE MARCINELLE TRAGEDY AND THE 25TH NATIONAL DAY OF THE SACRIFICE OF ITALIAN WORKERS IN THE WORLD. (Marcinelle, August 8, 2026)\">MESSAGE FROM THE VICE PRESIDENT OF THE COUNCIL OF MINISTERS AND MINISTER OF FOREIGN AFFAIRS AND INTERNATIONAL COOPERATION, ANTONIO TAJANI, ON THE OCCASION OF THE 70TH ANNIVERSARY OF THE MARCINELLE TRAGEDY AND THE 25TH NATIONAL DAY OF THE SACRIFICE OF ITALIAN WORKERS IN THE WORLD. (Marcinelle, August 8, 2026)<\/a><\/h5>\n                            <p class=\"card-text\">Seventy years ago, on August 8, 1956, Marcinelle entered forever into the collective memory of our country and Europe. In the Bois du Cazier pit, 262 workers of twelve nationalities lost their lives, 136 of whom were Italian. Today we remember them one by one. Behind those numbers were names, faces, families, hopes. Men who [&hellip;]<\/p>\n                                <a title=\"MESSAGE FROM THE VICE PRESIDENT OF THE COUNCIL OF MINISTERS AND MINISTER OF FOREIGN AFFAIRS AND INTERNATIONAL COOPERATION, ANTONIO TAJANI, ON THE OCCASION OF THE 70TH ANNIVERSARY OF THE MARCINELLE TRAGEDY AND THE 25TH NATIONAL DAY OF THE SACRIFICE OF ITALIAN WORKERS IN THE WORLD. (Marcinelle, August 8, 2026)\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/message-from-the-vice-president-of-the-council-of-ministers-and-minister-of-foreign-affairs-and-international-cooperation-antonio-tajani-on-the-occasion-of-the-70th-anniversary-of-the-marcinelle-tra\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 6 Agosto 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/bando-balcani-2026-chiusura-candidature-30-settembre-2026-h-1200-ora-di-roma\/\" title=\"Bando Balcani 2026. Chiusura candidature: 30 settembre 2026, h. 12:00 (ora di Roma)\">Bando Balcani 2026. Chiusura candidature: 30 settembre 2026, h. 12:00 (ora di Roma)<\/a><\/h5>\n                            <p class=\"card-text\">Il Ministero italiano degli Affari Esteri e della Cooperazione Internazionale (Direzione Generale per l\u2019Europa e la Politica Commerciale Internazionale \u2013 DGUE) ha pubblicato un avviso di pubblicit\u00e0 (Bando\u00a0Balcani 2026) in favore di progetti aventi la finalit\u00e0 di consentire la partecipazione italiana ad iniziative di pace ed umanitarie in sede internazionale e di tutela dei diritti [&hellip;]<\/p>\n                                <a title=\"Bando Balcani 2026. Chiusura candidature: 30 settembre 2026, h. 12:00 (ora di Roma)\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/bando-balcani-2026-chiusura-candidature-30-settembre-2026-h-1200-ora-di-roma\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 6 Agosto 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/visita-dell-on-vice-ministro-edmondo-cirielli-in-macedonia-del-nord\/\" title=\"Visita dell\u2019 On. Vice Ministro Edmondo Cirielli in Macedonia del Nord\">Visita dell\u2019 On. Vice Ministro Edmondo Cirielli in Macedonia del Nord<\/a><\/h5>\n                            <p class=\"card-text\">Lo scorso mercoled\u00ec 8 luglio il Vice Ministro degli Affari Esteri e la Cooperazione Internazionale On. Edmondo Cirielli si \u00e8 recato in visita a Skopje, accompagnato dal Direttore dell&#8217;Agenzia Italiana per la Cooperazione allo Sviluppo (AICS), dalla Direttrice dell\u2019Agenzia regionale, e da una delegazione diplomatica. Accompagnato dalla sua delegazione e dall&#8217;Ambasciatore d&#8217;Italia Paolo Palminteri, il [&hellip;]<\/p>\n                                <a title=\"Visita dell\u2019 On. Vice Ministro Edmondo Cirielli in Macedonia del Nord\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/visita-dell-on-vice-ministro-edmondo-cirielli-in-macedonia-del-nord\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 5 Agosto 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/know-how-exchange-programme-kep-of-the-central-european-initiative-call-for-proposals-2026\/\" title=\"Know-how Exchange Programme (KEP) of the Central European Initiative. Call for Proposals 2026\">Know-how Exchange Programme (KEP) of the Central European Initiative. Call for Proposals 2026<\/a><\/h5>\n                            <p class=\"card-text\">We are glad to announce the opening of the\u00a0Call for Proposals 2026\u00a0in the framework of the\u00a0Know-how Exchange Programme (KEP)\u00a0with funding made available by the\u00a0CEI Fund at the EBRD, entirely financed by the Italian Government. Launched in 2004, the KEP is a development instrument aimed at supporting the\u00a0transfer of expertise from organisations in the EU to [&hellip;]<\/p>\n                                <a title=\"Know-how Exchange Programme (KEP) of the Central European Initiative. Call for Proposals 2026\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/08\/know-how-exchange-programme-kep-of-the-central-european-initiative-call-for-proposals-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 16 Luglio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/07\/cessazione-della-validita-della-carta-didentita-cartacea-per-lespatrio-dal-3-agosto\/\" title=\"Cessazione della validit\u00e0 della carta d\u2019identit\u00e0 cartacea per l\u2019espatrio dal 3 agosto\">Cessazione della validit\u00e0 della carta d\u2019identit\u00e0 cartacea per l\u2019espatrio dal 3 agosto<\/a><\/h5>\n                            <p class=\"card-text\">A partire dal 3 agosto 2026 la versione cartacea della carta di identit\u00e0 cesser\u00e0 di essere valida per l\u2019espatrio, indipendentemente dalla data di scadenza riportata sul retro. Il DL 26\/06\/2026 n.108 ha introdotto alcune modifiche importanti: La Carta d\u2019Identit\u00e0 Cartacea non scaduta pu\u00f2 essere utilizzata come strumento identificativo nei rapporti con la Pubblica Amministrazione italiana [&hellip;]<\/p>\n                                <a title=\"Cessazione della validit\u00e0 della carta d\u2019identit\u00e0 cartacea per l\u2019espatrio dal 3 agosto\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/07\/cessazione-della-validita-della-carta-didentita-cartacea-per-lespatrio-dal-3-agosto\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 9 Luglio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/07\/avviso-di-assunzione-di-un-impiegato-a-a-contratto-temporaneo\/\" title=\"AVVISO DI ASSUNZIONE DI UN IMPIEGATO\/A A CONTRATTO TEMPORANEO\">AVVISO DI ASSUNZIONE DI UN IMPIEGATO\/A A CONTRATTO TEMPORANEO<\/a><\/h5>\n                            <p class=\"card-text\">L\u2019Ambasciata d\u2019Italia in Skopje ha indetto una procedura di selezione per l\u2019assunzione di n\u00b0 1 impiegato\/a a contratto temporaneo da adibire ai servizi di Assistente amministrativo. Tutti i dettagli sono contenuti nell&#8217;Avviso, reperibile al seguente link: Avviso di assunzione di un impiegato\/a a contratto temporaneo<\/p>\n                                <a title=\"AVVISO DI ASSUNZIONE DI UN IMPIEGATO\/A A CONTRATTO TEMPORANEO\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/07\/avviso-di-assunzione-di-un-impiegato-a-a-contratto-temporaneo\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 25 Giugno 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/06\/graduatoria-finale-del-bando-per-borse-di-studio-2026-2027-offerte-dalla-farnesina-per-studenti-stranieri-e-italiani-residenti-allestero\/\" title=\"Graduatoria Finale del Bando per Borse di Studio 2026\u20132027 offerte dalla Farnesina per studenti stranieri e italiani residenti all\u2019estero\">Graduatoria Finale del Bando per Borse di Studio 2026\u20132027 offerte dalla Farnesina per studenti stranieri e italiani residenti all\u2019estero<\/a><\/h5>\n                            <p class=\"card-text\">Si pubblica la Graduatoria finale relativa al Bando per Borse di studio offerte dal Governo italiano a studenti stranieri e italiani residenti all\u2019estero del Ministero degli Affari Esteri e della Cooperazione Internazionale: Graduatoria finale Bando Borse di studio 2026-2027 ____________________________________________ The final ranking list for the Scholarship Call offered by the Italian Government to foreign [&hellip;]<\/p>\n                                <a title=\"Graduatoria Finale del Bando per Borse di Studio 2026\u20132027 offerte dalla Farnesina per studenti stranieri e italiani residenti all\u2019estero\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/06\/graduatoria-finale-del-bando-per-borse-di-studio-2026-2027-offerte-dalla-farnesina-per-studenti-stranieri-e-italiani-residenti-allestero\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 5 Maggio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/05\/contributi-per-visite-di-ricercatori-docenti-esperti-personalita-e-operatori-culturali-e-f-2026\/\" title=\"Contributi per visite di ricercatori, docenti, esperti, personalit\u00e0 e operatori culturali e.f. 2026\">Contributi per visite di ricercatori, docenti, esperti, personalit\u00e0 e operatori culturali e.f. 2026<\/a><\/h5>\n                            <p class=\"card-text\">L\u2019Ufficio VI \u2013 DGCE eroga, a valere sul Cap. 2619\/7, contributi ad istanza di parte per: il finanziamento delle spese di viaggio e soggiorno di ricercatori, docenti, esperti, personalit\u00e0 della cultura e operatori culturali italiani o stranieri residenti in Italia da almeno due anni invitati all\u2019estero da Istituzioni universitarie o culturali straniere; contributi alle spese [&hellip;]<\/p>\n                                <a title=\"Contributi per visite di ricercatori, docenti, esperti, personalit\u00e0 e operatori culturali e.f. 2026\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/05\/contributi-per-visite-di-ricercatori-docenti-esperti-personalita-e-operatori-culturali-e-f-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 4 Maggio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/05\/contributi-a-enti-e-associazioni-per-corsi-di-formazione-e-aggiornamento-rivolti-a-docenti-di-lingua-italiana-nelle-scuole-locali\/\" title=\"CONTRIBUTI A ENTI E ASSOCIAZIONI PER CORSI DI FORMAZIONE E AGGIORNAMENTO RIVOLTI A DOCENTI DI LINGUA ITALIANA NELLE SCUOLE LOCALI\">CONTRIBUTI A ENTI E ASSOCIAZIONI PER CORSI DI FORMAZIONE E AGGIORNAMENTO RIVOLTI A DOCENTI DI LINGUA ITALIANA NELLE SCUOLE LOCALI<\/a><\/h5>\n                            <p class=\"card-text\">Il Ministero degli Affari Esteri e della Cooperazione Italiana (MAECI) ha lanciato un bando rivolto a scuole straniere e paritarie, Enti gestori\/promotori, Associazioni di scuole e Associazioni senza scopo di lucro per la concessione di contributi finanziari finalizzati alla promozione della lingua e cultura italiana nelle istituzioni scolastiche straniere &#8211; NON UNIVERSITARIE &#8211; attraverso l\u2019erogazione [&hellip;]<\/p>\n                                <a title=\"CONTRIBUTI A ENTI E ASSOCIAZIONI PER CORSI DI FORMAZIONE E AGGIORNAMENTO RIVOLTI A DOCENTI DI LINGUA ITALIANA NELLE SCUOLE LOCALI\" class=\"read-more\" href=\"https:\/\/ambskopje.esteri.it\/it\/news\/dall_ambasciata\/2026\/05\/contributi-a-enti-e-associazioni-per-corsi-di-formazione-e-aggiornamento-rivolti-a-docenti-di-lingua-italiana-nelle-scuole-locali\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">Paginazione<\/h2>\n                    <div class=\"nav-links\">\n                    <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/?pag=2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/?pag=3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/?pag=48\">48<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/?pag=2\"><svg class=\"icon icon-primary\"><use xlink:href=\"https:\/\/ambskopje.esteri.it\/wp-content\/themes\/sedi-tema\/assets\/svg\/sprites.svg#it-chevron-right\"><\/use><\/svg>\n                                    <span class=\"visually-hidden\">Pagina successiva<\/span><\/a>                    <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":16,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-33","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":1,"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/revisions"}],"predecessor-version":[{"id":34,"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/33\/revisions\/34"}],"up":[{"embeddable":true,"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/pages\/16"}],"wp:attachment":[{"href":"https:\/\/ambskopje.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}